{"id":5715,"date":"2024-01-13T23:46:31","date_gmt":"2024-01-13T23:46:31","guid":{"rendered":"https:\/\/blog.express-cbd.com\/o-oleo-cbd-e-legal-em-espanha\/"},"modified":"2024-01-26T12:26:09","modified_gmt":"2024-01-26T12:26:09","slug":"o-oleo-cbd-e-legal-em-espanha","status":"publish","type":"post","link":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/","title":{"rendered":"O \u00f3leo CBD \u00e9 legal em Espanha?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>As leis CBD de Espanha, explicadas<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Pode estar curioso: o \u00f3leo CBD \u00e9 legal em Espanha? Bem, a resposta pode surpreend\u00ea-lo&#8230; Embora alguns produtos com CBD sejam totalmente legais em Espanha e ao abrigo das regras da UE para os produtos com CBD, h\u00e1 uma s\u00e9rie de produtos com infus\u00e3o de CBD que ainda s\u00e3o ilegais em Espanha. Vamos mergulhar nos meandros da legisla\u00e7\u00e3o espanhola relativa aos produtos de CBD para descobrir tudo o que precisa de saber sobre o CBD em Espanha.  <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>O \u00f3leo CBD \u00e9 legal em Espanha?  <\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">No que diz respeito ao CDB em Espanha, a situa\u00e7\u00e3o n\u00e3o \u00e9 assim t\u00e3o negra e branca. A utiliza\u00e7\u00e3o e a produ\u00e7\u00e3o de produtos ricos em CBD s\u00e3o efetivamente legais no pa\u00eds. Mas h\u00e1 um sen\u00e3o &#8211; t\u00eam de ser concebidos <a href=\"https:\/\/blog.express-cbd.com\/pt-pt\/porque-e-que-uma-massagem-com-oleo-cbd-pode-ser-o-seu-novo-tratamento-de-spa-preferido\/\">exclusivamente para uso t\u00f3pico<\/a>. Pense em produtos de cuidados da pele, b\u00e1lsamos medicinais e \u00f3leos. O principal \u00f3rg\u00e3o regulador que supervisiona a regulamenta\u00e7\u00e3o dos produtos t\u00f3picos de CBD \u00e9 a <a href=\"https:\/\/globaledge.msu.edu\/global-resources\/resource\/10358\">Ag\u00eancia de Medicamentos<\/a>.  <\/p>\n\n<p class=\"wp-block-paragraph\">No entanto, \u00e9 aqui que as coisas se tornam interessantes. Contrariamente ao que poderia parecer uma proibi\u00e7\u00e3o absoluta, o CBD n\u00e3o \u00e9 abrangido pelos produtos regulamentados pelas autoridades espanholas que regem os suplementos nutricionais. Esta situa\u00e7\u00e3o \u00fanica cria uma zona cinzenta onde o CBD n\u00e3o \u00e9 explicitamente rotulado de legal ou ilegal.  <\/p>\n\n<p class=\"wp-block-paragraph\">A beleza dos regulamentos da UE e do Tribunal de Justi\u00e7a Europeu entra aqui em jogo. Gra\u00e7as a estes enquadramentos, os produtos de CBD podem ser obtidos legalmente em Espanha, mas com uma condi\u00e7\u00e3o espec\u00edfica. Devem ser importados de um pa\u00eds da UE onde o CBD \u00e9 autorizado para consumo e venda como suplemento nutricional (ou seja, Gr\u00e9cia ou Fran\u00e7a). \u00c9 fundamental que o produtor cumpra as normas legais do pa\u00eds de origem onde a produ\u00e7\u00e3o e a venda de CDB s\u00e3o autorizadas.  <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>\u00c9 seguro viajar para Espanha com CBD?<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Se est\u00e1 a planear uma viagem a Espanha e tenciona transportar produtos com CBD, \u00e9 aconselh\u00e1vel ter cuidado. Embora o CBD para uso t\u00f3pico seja permitido em Espanha, o transporte de CBD para fins de consumo pode encontrar obst\u00e1culos legais.  <\/p>\n\n<p class=\"wp-block-paragraph\">Para evitar potenciais problemas, \u00e9 aconselh\u00e1vel pesquisar e compreender bem os regulamentos espanh\u00f3is e os do pa\u00eds de partida no que respeita a viajar com produtos de CDB.  <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Quem regula o CBD em Espanha?<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">No dom\u00ednio do CBD em Espanha, v\u00e1rias entidades desempenham pap\u00e9is vitais na regulamenta\u00e7\u00e3o. <a href=\"https:\/\/www.who.int\/docs\/default-source\/controlled-substances\/whocbdreportmay2018-2.pdf?sfvrsn=f78db177_2\">A Organiza\u00e7\u00e3o Mundial de Sa\u00fade<\/a> (OMS) contribui com os seus conhecimentos e directrizes sobre a seguran\u00e7a e os potenciais benef\u00edcios do CBD. A <a href=\"https:\/\/www.efsa.europa.eu\/en\">Autoridade Europeia para a Seguran\u00e7a dos Alimentos<\/a> (EFSA) tamb\u00e9m d\u00e1 um contributo valioso, nomeadamente no que se refere aos aspectos de seguran\u00e7a do consumo de CDB.  <\/p>\n\n<p class=\"wp-block-paragraph\">A principal autoridade reguladora em Espanha \u00e9 a Ag\u00eancia de Medicamentos (AEMPS), respons\u00e1vel pela supervis\u00e3o dos produtos t\u00f3picos de CBD. Embora o estatuto do CBD em Espanha possa parecer um pouco amb\u00edguo, estes organismos reguladores trabalham em conjunto para navegar na paisagem legal em torno da utiliza\u00e7\u00e3o do CBD, garantindo a seguran\u00e7a e a conformidade dentro das fronteiras do pa\u00eds.  <\/p>\n\n<p class=\"wp-block-paragraph\">Essencialmente, o estatuto jur\u00eddico do CBD em Espanha \u00e9 matizado. Embora os produtos t\u00f3picos sejam considerados legais, a situa\u00e7\u00e3o continua a ser um pouco mais complicada para outros produtos de consumo. Existe o otimismo de que a UE, juntamente com estas outras organiza\u00e7\u00f5es, ir\u00e1 descobrir mais verdades sobre o CBD ao longo do tempo, o que poder\u00e1 acelerar a legaliza\u00e7\u00e3o. Mas, por enquanto, a Espanha joga pelo seguro com os calmantes t\u00f3picos de CBD.<\/p>\n\n\n<div class=\"row mb-5 border row-didpd\">\n  \n\n  <div class=\"col-lg-12 col-sm-12\">\n\n      <div class=\"row mb-1 \">\n\n        <div class=\"col-lg-12 col-sm-12 mt-5\">\n\n              <a href=\"https:\/\/express-cbd.com\"\n              target=\"_blank\"\n              class=\"btn btn-success  btn-didpd col-lg-12 col-sm-12 text-light mb-3 \">\n              Visit our Website              <\/a>\n        <\/div>\n\n      <\/div>\n  <\/div>\n<\/div>\n\n<p style=\"text-align: center\"><a href=\"https:\/\/express-cbd.com\" target=\"_blank\">Visit Express CBD Store<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>As leis CBD de Espanha, explicadas Pode estar curioso: o \u00f3leo CBD \u00e9 legal em Espanha? Bem, a resposta pode&#8230;<\/p>\n","protected":false},"author":3,"featured_media":3666,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[2747,2748,81,83,2749],"class_list":["post-5715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cbd-pt-pt","tag-balsamo-de-cbd","tag-bomba-de-banho-cbd","tag-cbd-beleza","tag-cuidados-de-pele-cbd","tag-leis-cbd-espanha"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>O \u00f3leo CBD \u00e9 legal em Espanha? - Express CBD Blog<\/title>\n<meta name=\"description\" content=\"O \u00f3leo CBD \u00e9 legal em Espanha? A resposta pode surpreender-te. Saiba todos os detalhes sobre a legisla\u00e7\u00e3o atual relativa ao CBD em Espanha.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O \u00f3leo CBD \u00e9 legal em Espanha?\" \/>\n<meta property=\"og:description\" content=\"O \u00f3leo CBD \u00e9 legal em Espanha? A resposta pode surpreender-te. Saiba todos os detalhes sobre a legisla\u00e7\u00e3o atual relativa ao CBD em Espanha.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/\" \/>\n<meta property=\"og:site_name\" content=\"Express CBD Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-13T23:46:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-26T12:26:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.express-cbd.com\/wp-content\/uploads\/2023\/11\/Untitled-design-28.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Express CBD Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ExpressCBDCom\" \/>\n<meta name=\"twitter:site\" content=\"@ExpressCBDCom\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Express CBD Blog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/\"},\"author\":{\"name\":\"Express CBD Blog\",\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/fc10918a8de6cc86135fbc04c7b820f4\"},\"headline\":\"O \u00f3leo CBD \u00e9 legal em Espanha?\",\"datePublished\":\"2024-01-13T23:46:31+00:00\",\"dateModified\":\"2024-01-26T12:26:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/\"},\"wordCount\":652,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.express-cbd.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Untitled-design-28.png\",\"keywords\":[\"b\u00e1lsamo de cbd\",\"bomba de banho cbd\",\"cbd beleza\",\"cuidados de pele cbd\",\"leis cbd espanha\"],\"articleSection\":[\"CBD\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/\",\"url\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/\",\"name\":\"O \u00f3leo CBD \u00e9 legal em Espanha? - Express CBD Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.express-cbd.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Untitled-design-28.png\",\"datePublished\":\"2024-01-13T23:46:31+00:00\",\"dateModified\":\"2024-01-26T12:26:09+00:00\",\"description\":\"O \u00f3leo CBD \u00e9 legal em Espanha? A resposta pode surpreender-te. Saiba todos os detalhes sobre a legisla\u00e7\u00e3o atual relativa ao CBD em Espanha.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.express-cbd.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Untitled-design-28.png\",\"contentUrl\":\"https:\\\/\\\/blog.express-cbd.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Untitled-design-28.png\",\"width\":940,\"height\":788,\"caption\":\"The current laws in Spain prohibit the sale of CBD products unless they are for topical use only.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/o-oleo-cbd-e-legal-em-espanha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Express CBD Blog\",\"item\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O \u00f3leo CBD \u00e9 legal em Espanha?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/\",\"name\":\"Express CBD Blog\",\"description\":\"Informa\u00e7\u00f5es e dicas de especialistas sobre CBD\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/#organization\",\"name\":\"Express CBD Blog\",\"url\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.express-cbd.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Express-CBD-Blog.png\",\"contentUrl\":\"https:\\\/\\\/blog.express-cbd.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Express-CBD-Blog.png\",\"width\":3596,\"height\":2154,\"caption\":\"Express CBD Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/ExpressCBDCom\",\"https:\\\/\\\/www.threads.com\\\/@expresscbdcom\",\"https:\\\/\\\/www.instagram.com\\\/expresscbdcom\"],\"description\":\"Express CBD is a UK online shop offering premium CBD oils, capsules, vapes, edibles, skincare, and vaping products from hundreds of trusted brands.\",\"email\":\"info@express-cbd.com\",\"legalName\":\"Express CBD\",\"foundingDate\":\"2023-03-02\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"publishingPrinciples\":\"https:\\\/\\\/blog.express-cbd.com\\\/publishing-principles\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/blog.express-cbd.com\\\/ownership-funding\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/blog.express-cbd.com\\\/feedback\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/blog.express-cbd.com\\\/corrections-policy\\\/\",\"ethicsPolicy\":\"https:\\\/\\\/blog.express-cbd.com\\\/ethics-policy\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/fc10918a8de6cc86135fbc04c7b820f4\",\"name\":\"Express CBD Blog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/927d7de299dd0125dac1d0314a27c38bb70335721bf666f644f872eddd36a3ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/927d7de299dd0125dac1d0314a27c38bb70335721bf666f644f872eddd36a3ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/927d7de299dd0125dac1d0314a27c38bb70335721bf666f644f872eddd36a3ed?s=96&d=mm&r=g\",\"caption\":\"Express CBD Blog\"},\"url\":\"https:\\\/\\\/blog.express-cbd.com\\\/pt-pt\\\/author\\\/express-cbd-blog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O \u00f3leo CBD \u00e9 legal em Espanha? - Express CBD Blog","description":"O \u00f3leo CBD \u00e9 legal em Espanha? A resposta pode surpreender-te. Saiba todos os detalhes sobre a legisla\u00e7\u00e3o atual relativa ao CBD em Espanha.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/","og_locale":"pt_PT","og_type":"article","og_title":"O \u00f3leo CBD \u00e9 legal em Espanha?","og_description":"O \u00f3leo CBD \u00e9 legal em Espanha? A resposta pode surpreender-te. Saiba todos os detalhes sobre a legisla\u00e7\u00e3o atual relativa ao CBD em Espanha.","og_url":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/","og_site_name":"Express CBD Blog","article_published_time":"2024-01-13T23:46:31+00:00","article_modified_time":"2024-01-26T12:26:09+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/blog.express-cbd.com\/wp-content\/uploads\/2023\/11\/Untitled-design-28.png","type":"image\/png"}],"author":"Express CBD Blog","twitter_card":"summary_large_image","twitter_creator":"@ExpressCBDCom","twitter_site":"@ExpressCBDCom","twitter_misc":{"Escrito por":"Express CBD Blog","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/#article","isPartOf":{"@id":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/"},"author":{"name":"Express CBD Blog","@id":"https:\/\/blog.express-cbd.com\/pt-pt\/#\/schema\/person\/fc10918a8de6cc86135fbc04c7b820f4"},"headline":"O \u00f3leo CBD \u00e9 legal em Espanha?","datePublished":"2024-01-13T23:46:31+00:00","dateModified":"2024-01-26T12:26:09+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/"},"wordCount":652,"commentCount":0,"publisher":{"@id":"https:\/\/blog.express-cbd.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.express-cbd.com\/wp-content\/uploads\/2023\/11\/Untitled-design-28.png","keywords":["b\u00e1lsamo de cbd","bomba de banho cbd","cbd beleza","cuidados de pele cbd","leis cbd espanha"],"articleSection":["CBD"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/","url":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/","name":"O \u00f3leo CBD \u00e9 legal em Espanha? - Express CBD Blog","isPartOf":{"@id":"https:\/\/blog.express-cbd.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/#primaryimage"},"image":{"@id":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.express-cbd.com\/wp-content\/uploads\/2023\/11\/Untitled-design-28.png","datePublished":"2024-01-13T23:46:31+00:00","dateModified":"2024-01-26T12:26:09+00:00","description":"O \u00f3leo CBD \u00e9 legal em Espanha? A resposta pode surpreender-te. Saiba todos os detalhes sobre a legisla\u00e7\u00e3o atual relativa ao CBD em Espanha.","breadcrumb":{"@id":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/#primaryimage","url":"https:\/\/blog.express-cbd.com\/wp-content\/uploads\/2023\/11\/Untitled-design-28.png","contentUrl":"https:\/\/blog.express-cbd.com\/wp-content\/uploads\/2023\/11\/Untitled-design-28.png","width":940,"height":788,"caption":"The current laws in Spain prohibit the sale of CBD products unless they are for topical use only."},{"@type":"BreadcrumbList","@id":"https:\/\/blog.express-cbd.com\/pt-pt\/o-oleo-cbd-e-legal-em-espanha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Express CBD Blog","item":"https:\/\/blog.express-cbd.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"O \u00f3leo CBD \u00e9 legal em Espanha?"}]},{"@type":"WebSite","@id":"https:\/\/blog.express-cbd.com\/pt-pt\/#website","url":"https:\/\/blog.express-cbd.com\/pt-pt\/","name":"Express CBD Blog","description":"Informa\u00e7\u00f5es e dicas de especialistas sobre CBD","publisher":{"@id":"https:\/\/blog.express-cbd.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.express-cbd.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/blog.express-cbd.com\/pt-pt\/#organization","name":"Express CBD Blog","url":"https:\/\/blog.express-cbd.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.express-cbd.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/blog.express-cbd.com\/wp-content\/uploads\/2023\/04\/Express-CBD-Blog.png","contentUrl":"https:\/\/blog.express-cbd.com\/wp-content\/uploads\/2023\/04\/Express-CBD-Blog.png","width":3596,"height":2154,"caption":"Express CBD Blog"},"image":{"@id":"https:\/\/blog.express-cbd.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/ExpressCBDCom","https:\/\/www.threads.com\/@expresscbdcom","https:\/\/www.instagram.com\/expresscbdcom"],"description":"Express CBD is a UK online shop offering premium CBD oils, capsules, vapes, edibles, skincare, and vaping products from hundreds of trusted brands.","email":"info@express-cbd.com","legalName":"Express CBD","foundingDate":"2023-03-02","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"publishingPrinciples":"https:\/\/blog.express-cbd.com\/publishing-principles\/","ownershipFundingInfo":"https:\/\/blog.express-cbd.com\/ownership-funding\/","actionableFeedbackPolicy":"https:\/\/blog.express-cbd.com\/feedback\/","correctionsPolicy":"https:\/\/blog.express-cbd.com\/corrections-policy\/","ethicsPolicy":"https:\/\/blog.express-cbd.com\/ethics-policy\/"},{"@type":"Person","@id":"https:\/\/blog.express-cbd.com\/pt-pt\/#\/schema\/person\/fc10918a8de6cc86135fbc04c7b820f4","name":"Express CBD Blog","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/927d7de299dd0125dac1d0314a27c38bb70335721bf666f644f872eddd36a3ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/927d7de299dd0125dac1d0314a27c38bb70335721bf666f644f872eddd36a3ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/927d7de299dd0125dac1d0314a27c38bb70335721bf666f644f872eddd36a3ed?s=96&d=mm&r=g","caption":"Express CBD Blog"},"url":"https:\/\/blog.express-cbd.com\/pt-pt\/author\/express-cbd-blog\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.express-cbd.com\/pt-pt\/wp-json\/wp\/v2\/posts\/5715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.express-cbd.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.express-cbd.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.express-cbd.com\/pt-pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.express-cbd.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=5715"}],"version-history":[{"count":2,"href":"https:\/\/blog.express-cbd.com\/pt-pt\/wp-json\/wp\/v2\/posts\/5715\/revisions"}],"predecessor-version":[{"id":5731,"href":"https:\/\/blog.express-cbd.com\/pt-pt\/wp-json\/wp\/v2\/posts\/5715\/revisions\/5731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.express-cbd.com\/pt-pt\/wp-json\/wp\/v2\/media\/3666"}],"wp:attachment":[{"href":"https:\/\/blog.express-cbd.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=5715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.express-cbd.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=5715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.express-cbd.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=5715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}